{"id":1595,"date":"2021-11-22T07:21:23","date_gmt":"2021-11-22T07:21:23","guid":{"rendered":"https:\/\/www.ur-textiles.com\/?p=1595"},"modified":"2022-03-24T06:43:24","modified_gmt":"2022-03-24T06:43:24","slug":"chiffon-fabrics-news2","status":"publish","type":"post","link":"https:\/\/ur-textiles.com\/fr\/chiffon-fabrics-news2\/","title":{"rendered":"Comment entretenir les tissus mousseline ?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1595\" class=\"elementor elementor-1595\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28f71369 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28f71369\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12b7bbab\" data-id=\"12b7bbab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e6d5dc uael-heading-align-left elementor-widget elementor-widget-uael-table-of-contents\" data-id=\"5e6d5dc\" data-element_type=\"widget\" data-settings=\"{&quot;heading_text_align&quot;:&quot;left&quot;,&quot;heading_bottom_space&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;heading_bottom_space_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;heading_bottom_space_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;separator_bottom_space&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;separator_bottom_space_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;separator_bottom_space_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;content_between_space&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;content_between_space_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;content_between_space_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"uael-table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"uael-toc-main-wrapper\" data-headings=\"h1,h2,h3\" >\n\t\t\t<div class=\"uael-toc-wrapper\">\n\t\t\t\t<div class=\"uael-toc-header\">\n\t\t\t\t\t<span class=\"uael-toc-heading elementor-inline-editing\" data-elementor-setting-key=\"heading_title\" data-elementor-inline-editing-toolbar=\"basic\" >Table des mati\u00e8res<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-toc-toggle-content\">\n\t\t\t\t\t<div class=\"uael-toc-content-wrapper\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t<ul data-toc-headings=\"headings\" class=\"uael-toc-list uael-toc-list-disc\" data-scroll=\"\" ><\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"uael-toc-empty-note\">\n\t\t\t\t\t<span data-no-translation=\"\" data-trp-gettext=\"\">\u0623\u0636\u0641 \u0631\u0623\u0633\u064b\u0627 \u0644\u0628\u062f\u0621 \u0625\u0646\u0634\u0627\u0621 \u062c\u062f\u0648\u0644 \u0627\u0644\u0645\u062d\u062a\u0648\u064a\u0627\u062a<\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-443ed025 elementor-widget elementor-widget-text-editor\" data-id=\"443ed025\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p><a href=\"https:\/\/ur-textiles.com\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tissus en mousseline de soie<\/a> appartient \u00e0 la fibre de soins de sant\u00e9 d\u00e9licate des prot\u00e9ines, il ne convient donc pas de frotter avec des articles rugueux pendant le lavage.<\/p>\n\n\n\n<p>Les v\u00eatements en tissu de soie doivent \u00eatre immerg\u00e9s dans l&#039;eau froide pendant 5 \u00e0 10 minutes, frott\u00e9s doucement avec un d\u00e9tergent sp\u00e9cial pour tissus de soie ou du savon neutre, puis blanchis et lav\u00e9s \u00e0 plusieurs reprises \u00e0 l&#039;eau claire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Les tissus en mousseline vont-ils r\u00e9tr\u00e9cir ?<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>Les tissus en mousseline de soie sont divis\u00e9s en deux types : l&#039;un est en polyester et l&#039;autre en soie. Le r\u00e9tr\u00e9cissement des deux est tr\u00e8s diff\u00e9rent.<\/p>\n\n\n\n<p>Mousseline de polyester\u00a0: il n&#039;y a pas de r\u00e9tr\u00e9cissement et le r\u00e9tr\u00e9cissement des produits finis peut \u00eatre contr\u00f4l\u00e9 dans 3%\u00a0;<\/p>\n\n\n\n<p>Mousseline de soie\u00a0: en raison de la torsion \u00e9lev\u00e9e, de la structure l\u00e2che du tissu et du retrait important, si le produit fini n&#039;a pas \u00e9t\u00e9 pr\u00e9-r\u00e9tr\u00e9ci, le retrait au lavage \u00e0 l&#039;eau peut atteindre plus de 10%\u00a0;<\/p>\n\n\n\n<p>Cependant, les fabricants effectuent g\u00e9n\u00e9ralement une finition avant retrait et le taux de retrait des produits finis est d&#039;environ 5%\u00a0;<\/p>\n\n\n\n<p>Par cons\u00e9quent, si vous rencontrez des tissus en soie, vous devez les laver \u00e0 l&#039;eau froide lors de leur lavage.<\/p>\n\n\n\n<p>Ils sont g\u00e9n\u00e9ralement s\u00e9ch\u00e9s \u00e0 l&#039;air et ne peuvent pas \u00eatre s\u00e9ch\u00e9s. De cette fa\u00e7on, le r\u00e9tr\u00e9cissement sera bien meilleur.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"523\" height=\"344\" src=\"https:\/\/ur-textiles.com\/wp-content\/uploads\/2021\/08\/0813.png\" alt=\"chiffon fabric\" class=\"wp-image-1028\" title=\"\" srcset=\"https:\/\/ur-textiles.com\/wp-content\/uploads\/2021\/08\/0813.png 523w, https:\/\/ur-textiles.com\/wp-content\/uploads\/2021\/08\/0813-300x197.png 300w, https:\/\/ur-textiles.com\/wp-content\/uploads\/2021\/08\/0813-18x12.png 18w\" sizes=\"(max-width: 523px) 100vw, 523px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quels sont les types de tissus mousseline ?<\/strong><\/h3>\n\n\n\n<p>Les tissus en mousseline peuvent \u00eatre compos\u00e9s de soie, de coton, de nylon, de polyester ou de rayonne. Selon les diff\u00e9rents tissus, le prix des v\u00eatements en mousseline de soie sera diff\u00e9rent.<\/p>\n\n\n\n<p>Les tissus en mousseline de soie sont les plus pr\u00e9cieux car la soie a un lustre riche et une texture lisse.<\/p>\n\n\n\n<p>La mousseline de soie est tr\u00e8s l\u00e9g\u00e8re. Parce que la mousseline de soie est un tulle en fibre de soie naturelle, elle est souvent plus ch\u00e8re et n\u00e9cessite un environnement de stockage sec et propre.<\/p>\n\n\n\n<p>La soie peut \u00e9galement \u00eatre utilis\u00e9e pour faire de la georgette, parfois appel\u00e9e cr\u00eape.<\/p>\n\n\n\n<p>Le tissu est \u00e9pais, comme un tissu de rideau opaque, mais il est \u00e9galement doux et l\u00e9ger comme de la mousseline de soie.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelle est la diff\u00e9rence entre le tissu mousseline et la maille mousseline ?<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>Le tissu en mousseline de soie est une sorte de tissu en soie compos\u00e9 d&#039;une cha\u00eene de cr\u00eape et d&#039;une trame de cr\u00eape \u00e0 forte torsion.<\/p>\n\n\n\n<p>La mousseline de soie a une texture l\u00e9g\u00e8re et transparente, une sensation douce et \u00e9lastique, une apparence l\u00e9g\u00e8re et \u00e9l\u00e9gante, une bonne perm\u00e9abilit\u00e9 \u00e0 l&#039;air et une bonne drapabilit\u00e9, un port \u00e9l\u00e9gant et confortable.<\/p>\n\n\n\n<p>La maille est une fine armure toile tiss\u00e9e avec un fil torsad\u00e9 fin et r\u00e9sistant.<\/p>\n\n\n\n<p>Ses caract\u00e9ristiques sont : densit\u00e9 clairsem\u00e9e, texture fine, trous de marche clairs, sensation de main fra\u00eeche, pleine d&#039;\u00e9lasticit\u00e9, bonne perm\u00e9abilit\u00e9 \u00e0 l&#039;air et port confortable.<\/p>\n\n\n\n<p>On l&#039;appelle aussi fil de Bali en raison de sa bonne transparence. Le fil de Bali, \u00e9galement connu sous le nom de fil de verre, est appel\u00e9 voile en anglais.<\/p>\n\n\n\n<p>Un fil de torsion fort fin et extra peign\u00e9 est adopt\u00e9 pour la cha\u00eene et la trame, et la densit\u00e9 de la cha\u00eene et de la trame dans le tissu est relativement faible.<\/p>\n\n\n\n<p>En raison de la torsion \u00abfine\u00bb, \u00abfine\u00bb et forte, le tissu est fin et transparent.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Table of Contents Add a header to begin generating the table of contents Chiffon fabrics belongs to protein delicate health care fiber, so it is not suitable to rub with rough articles during washing. Silk fabric clothes should be immersed in cold water for 5-10 minutes, gently rubbed with special silk fabric detergent or neutral [&hellip;]<\/p>","protected":false},"author":2,"featured_media":1028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[64],"class_list":["post-1595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-chiffon-fabrics"],"_links":{"self":[{"href":"https:\/\/ur-textiles.com\/fr\/wp-json\/wp\/v2\/posts\/1595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ur-textiles.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ur-textiles.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ur-textiles.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ur-textiles.com\/fr\/wp-json\/wp\/v2\/comments?post=1595"}],"version-history":[{"count":4,"href":"https:\/\/ur-textiles.com\/fr\/wp-json\/wp\/v2\/posts\/1595\/revisions"}],"predecessor-version":[{"id":1599,"href":"https:\/\/ur-textiles.com\/fr\/wp-json\/wp\/v2\/posts\/1595\/revisions\/1599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ur-textiles.com\/fr\/wp-json\/wp\/v2\/media\/1028"}],"wp:attachment":[{"href":"https:\/\/ur-textiles.com\/fr\/wp-json\/wp\/v2\/media?parent=1595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ur-textiles.com\/fr\/wp-json\/wp\/v2\/categories?post=1595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ur-textiles.com\/fr\/wp-json\/wp\/v2\/tags?post=1595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}